{"id":171,"date":"2011-04-28T16:10:28","date_gmt":"2011-04-28T16:10:28","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=171"},"modified":"2011-04-28T16:12:44","modified_gmt":"2011-04-28T16:12:44","slug":"la-hora-del-planeta-y-pocoyo","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/ar\/la-hora-del-planeta-y-pocoyo\/","title":{"rendered":"\u0633\u0627\u0639\u0629 \u0627\u0644\u0623\u0631\u0636 \u0648\u0628\u0648\u0643\u0648\u064a\u0648"},"content":{"rendered":"<p style=\"text-align: justify;\">\u0644\u0627 \u0623\u0633\u062a\u0637\u064a\u0639 \u0627\u0644\u062a\u0648\u0642\u0641 \u0639\u0646 \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0641\u064a \u0646\u0645\u0648 \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0633\u0646\u0648\u0627\u062a \u0627\u0644\u0623\u062e\u064a\u0631\u0629 \u0648\u0627\u0644\u0639\u0648\u0627\u0642\u0628 \u0627\u0644\u062a\u064a \u0633\u062a\u062a\u0631\u062a\u0628 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0623\u062c\u064a\u0627\u0644 \u0627\u0644\u0642\u0627\u062f\u0645\u0629.<!--more--><\/p>\n<p style=\"text-align: justify;\">Nosotros mismos, que todav\u00eda nos consideramos unos chavales aunque vamos ya acerc\u00e1ndonos a los 50, la generaci\u00f3n que nacimos en los 60, podemos recordar y seguro que recordamos, momentos vividos en contacto con la \u00a0naturaleza, en los diversos puntos del mundo de los que somos cada uno de nosotros o que hemos tenido la oportunidad de visitar, que probablemente nuestros hijos no podr\u00e1n vivir de la misma manera y con la misma experiencia con la que nosotros la vivimos. Me sangra el alma de pensarlo.<\/p>\n<p style=\"text-align: justify;\">Esta es una de las razones por las que desde <a href=\"http:\/\/www.zinkia.com\">\u0632\u0646\u0643\u064a\u0629 <\/a>y en concreto con <a href=\"http:\/\/www.pocoyo.com\">\u0628\u0648\u0643\u0648\u064a\u0648<\/a>, no podemos dejar de apoyar la causa de la naturaleza y el cuidado de nuestro Planeta. Tenemos que traspasar a nuestros hijos el aprecio, el respeto y el cari\u00f1o por nuestra Tierra, por nuestra naturaleza y por todos los ecosistemas que disfrutamos, pero que si no cuidamos, simplemente se perder\u00e1n y las futuras generaciones no podr\u00e1n disfrutarlos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/clip_image0012.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-173\" title=\"clip_image001\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/clip_image0012-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/clip_image0012-300x224.jpg 300w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/clip_image0012-1024x764.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><em><strong>En esta foto aparezco junto con Pocoy\u00f3 en Singapur, momentos despu\u00e9s de presentar p\u00fablicamente <a href=\"http:\/\/www.horadelplaneta.es\/\">\u0633\u0627\u0639\u0629 \u0627\u0644\u0623\u0631\u0636<\/a>, una iniciativa respaldada desde el <a href=\"http:\/\/www.wwf.es\/\">\u0627\u0644\u0635\u0646\u062f\u0648\u0642 \u0627\u0644\u0639\u0627\u0644\u0645\u064a \u0644\u0644\u0637\u0628\u064a\u0639\u0629<\/a> con el fin de ayudar en este proceso de concienciaci\u00f3n.<\/strong><\/em><em><strong> <\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0644\u0627 \u0623\u0633\u062a\u0637\u064a\u0639 \u0627\u0644\u062a\u0648\u0642\u0641 \u0639\u0646 \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0641\u064a \u0646\u0645\u0648 \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0633\u0646\u0648\u0627\u062a \u0627\u0644\u0623\u062e\u064a\u0631\u0629 \u0648\u0627\u0644\u0639\u0648\u0627\u0642\u0628 \u0627\u0644\u062a\u064a \u0633\u062a\u062a\u0631\u062a\u0628 \u0639\u0644\u0649 \u0630\u0644\u0643 \u0628\u0627\u0644\u0646\u0633\u0628\u0629 \u0644\u0644\u0623\u062c\u064a\u0627\u0644 \u0627\u0644\u0642\u0627\u062f\u0645\u0629.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-171","post","type-post","status-publish","format-standard","hentry","category-pocoyo"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":4,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"predecessor-version":[{"id":176,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/posts\/171\/revisions\/176"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ar\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}