{"id":1024,"date":"2012-06-14T14:24:01","date_gmt":"2012-06-14T14:24:01","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=1024"},"modified":"2012-06-14T14:24:01","modified_gmt":"2012-06-14T14:24:01","slug":"tharman-shanmugaratnam","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/en\/tharman-shanmugaratnam\/","title":{"rendered":"Tharman Shanmugaratnam"},"content":{"rendered":"<p style=\"text-align: justify;\">Hace unos d\u00edas tuve la oportunidad, invitado por el <a href=\"http:\/\/www.ie.edu\/\">Instituto de Empresa<\/a>, de asistir en Madrid a una comida presidida por el Vice Primer Ministro de Singapur, tambi\u00e9n Ministro de Finanzas y Ministro de Recursos Humanos, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Tharman_Shanmugaratnam\">Tharman Shanmugaratnam.<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/06\/Tharman_Shanmugaratnam_at_the_official_opening_of_Yuan_Ching_Secondary_Schools_new_building_Singapore_-_20100716_cropped1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1027\" title=\"Tharman_Shanmugaratnam_at_the_official_opening_of_Yuan_Ching_Secondary_School's_new_building,_Singapore_-_20100716_(cropped)\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/06\/Tharman_Shanmugaratnam_at_the_official_opening_of_Yuan_Ching_Secondary_Schools_new_building_Singapore_-_20100716_cropped1-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/06\/Tharman_Shanmugaratnam_at_the_official_opening_of_Yuan_Ching_Secondary_Schools_new_building_Singapore_-_20100716_cropped1-200x300.jpg 200w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/06\/Tharman_Shanmugaratnam_at_the_official_opening_of_Yuan_Ching_Secondary_Schools_new_building_Singapore_-_20100716_cropped1.jpg 464w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--more-->Antes de ocupar los cargos pol\u00edticos que comentaba, estudi\u00f3 en la <a href=\"http:\/\/www2.lse.ac.uk\/home.aspx\">London School of Economics<\/a>, obtuvo un Master en Administraci\u00f3n P\u00fablica en Harvard y desarroll\u00f3 la primera parte de su carrera en el Monetary Authority of Singapore, del que lleg\u00f3 a ser CEO. De ah\u00ed pas\u00f3 a presidir el <a href=\"http:\/\/www.imf.org\/external\/np\/exr\/facts\/groups.htm\">International Monetary and Financial Committee<\/a>, organismo interno del IMF y desde 2007 es Ministro de Finanzas de Singapur.<\/p>\n<p style=\"text-align: justify;\">Fue una comida muy agradable, durante la cual nos estuvo contando su visi\u00f3n sobre el proceso por el que atravesamos en el mundo y estuvo compartiendo con nosotros sus razonamientos. Adem\u00e1s con el m\u00e9rito a\u00f1adido de, tal y como bien demostr\u00f3 durante la charla, no tenerla preparada. Nos dijo que ven\u00eda preparado para dirigirse a una audiencia de estudiantes de Post Grado y se encontr\u00f3 con una audiencia de empresarios y gestores. Habl\u00f3 durante algo m\u00e1s de una hora de una manera clara, concisa y perfectamente organizada y en ning\u00fan momento mir\u00f3 un papel, un gui\u00f3n o algo que se le pareciera.<\/p>\n<p style=\"text-align: justify;\">Voy a intentar en los pr\u00f3ximos p\u00e1rrafos, resumir de todo aquello de lo que nos estuvo comentando.<\/p>\n<p style=\"text-align: justify;\">De lo primero que nos habl\u00f3 fue de la necesidad e importancia de la confianza, para poder generar crecimiento. Si no hay confianza entre los ciudadanos tanto de los Estados Unidos de Am\u00e9rica, como de Europa, ser\u00e1 muy dif\u00edcil volver a construir crecimiento a largo plazo. Y de qu\u00e9 manera est\u00e1 evidenci\u00e1ndose en estos d\u00edas especialmente!.<\/p>\n<p style=\"text-align: justify;\">Una vez aclarada la importancia de la <strong>trust<\/strong>, hay tener claro tambi\u00e9n que el mundo es cada vez m\u00e1s un mundo global. Pero la <strong>globalizaci\u00f3n<\/strong> conlleva un gran riesgo que pocos parecen estar teniendo en cuenta: el juego de ganadores y perdedores. Hablar de un <strong>mundo global <\/strong>es hablar de un mundo en <strong>competencia.<\/strong> Y especialmente en estos momentos, en feroz competencia por unos recursos que cada vez aparecen como m\u00e1s limitados. Y si los pol\u00edticos no intervienen con clarividencia en este proceso, la consecuencia podr\u00eda ser muy negativa. En un entorno global, no se debe poner a la <strong>sociedad<\/strong> y en particular las diferentes sociedades nacionales, en manos de sistemas financieros desregulados, donde son los especuladores quienes mejor campan a sus anchas. La Ley debe intervenir para proteger el futuro de los <strong>ciudadanos<\/strong> y hacerlo sin ser excesivamente intervencionista.<\/p>\n<p style=\"text-align: justify;\">Nos enfrentamos claramente a un momento de gran cambio en la forma de entender las relaciones sociales, econ\u00f3micas y pol\u00edticas en el mundo. Algo que, mientras lo o\u00eda, me hac\u00eda recordar los finales del siglo XVIII, cuando el mundo se encontraba en tan poco tiempo con cambios tan radicales y que luego transformaron la sociedad hasta convertirla en la que nosotros, 250 a\u00f1os despu\u00e9s, seguimos conociendo. Parece que se est\u00e1 cerrando este ciclo que se abri\u00f3 entonces y se comienza a vislumbrar el arranque de otro nuevo.<\/p>\n<p style=\"text-align: justify;\">Pero volvamos al discurso de Mr. Shanmugaratnam. Los gobiernos deber\u00edan adelantar a las empresas y a los<strong> mercados <\/strong>con la oportunidad de la <strong>crisis<\/strong>.Deber\u00edan aportar un mucho mayor protagonismo, pero con unas ideas mucho m\u00e1s claras de lo que las tienen. Los pa\u00edses emergentes tienen serios problemas estructurales, algo perfectamente conocido y los pa\u00edses desarrollados tienen en una amplia mayor\u00eda, enormes problemas financieros a corto y largo plazo y tambi\u00e9n grandes problemas demogr\u00e1ficos.<\/p>\n<p style=\"text-align: justify;\">Llegados a este punto es cuando se produce la discusi\u00f3n entre austeridad y crecimiento.\u00a0 Pero se deber\u00eda ir m\u00e1s adelante. No hay que ser tan simplista. No se trata de plantear s\u00f3lo pol\u00edticas dirigidas a fomentar la demanda o el <strong>consumo<\/strong>, esto es algo que est\u00e1 demostrando no funcionar. Y tampoco pol\u00edticas dirigidas a construir, modificar o reformar las infraestructuras.\u00a0 Tambi\u00e9n est\u00e1 demostrando ser algo que no funciona.<\/p>\n<p style=\"text-align: justify;\">Se trata de trabajar en el corto plazo, con visi\u00f3n de largo plazo. Para eso hay que poner en el centro al individuo. Al ciudadano.\u00a0 Hay que desarrollar la <strong>competitividad,<\/strong> fomentar la <strong>creatividad <\/strong>\u2013que como muy bien dec\u00eda Einstein s\u00f3lo nace cuando se est\u00e1 bajo el influjo de potentes crisis- , y modificar el planteamiento de los Estados que se ven s\u00f3lo actuando sobre est\u00edmulos fiscales, est\u00edmulos de liquidez y aceptaci\u00f3n de d\u00e9ficits fiscales.<\/p>\n<p style=\"text-align: justify;\">Una vez m\u00e1s, se trata de poner al individuo en el centro. Si hay algo a lo que no se puede renunciar a la hora de hablar de la globalizaci\u00f3n, es a la personalidad de cada uno de los Estados y con ella, a la de cada uno de los ciudadanos que conforman esos Estados \u00fanicos y hay que trabajar con la visi\u00f3n de un proyecto social y econ\u00f3mico, no s\u00f3lo competitivo.<\/p>\n<p style=\"text-align: justify;\">El viejo juego deber\u00eda quedar claro que ha quedado superado. El <strong>mercado<\/strong> no puede, ni debe ser, quien establezca las reglas. Ha quedado m\u00e1s que claro que es algo demasiado injusto. Y los individuos, cada vez m\u00e1s conscientes del poder que en ellos individualmente reside, est\u00e1n siendo cada vez m\u00e1s testigos activos de ello. No podemos pensar que la pasividad que hasta ahora se ha visto, vaya a ser la t\u00f3nica general en el futuro.<\/p>\n<p style=\"text-align: justify;\">Los Estados han de comenzar a plantearse ser activos en \u00e1reas en las que actualmente no lo est\u00e1n siendo:<\/p>\n<p style=\"text-align: justify;\">1.- Fomentar la <strong>movilidad social.\u00a0<\/strong> Esto afecta tanto a la educaci\u00f3n, el entretenimiento y las diferentes oportunidades laborales y familiares.<\/p>\n<p style=\"text-align: justify;\">2.- Invertir en personas: aprovechar las <strong>oportunidades<\/strong> y no los t\u00edtulos de formaci\u00f3n<\/p>\n<p style=\"text-align: justify;\">3.- Promover las culturas propias y all\u00ed donde no existan, desarrollarlas.<\/p>\n<p style=\"text-align: justify;\">4.- Focalizarse en las capacidades que crean valor, las que sean m\u00e1s \u00fanicas<\/p>\n<p style=\"text-align: justify;\">5.- Fomentar la unidad social entre las personas<\/p>\n<p style=\"text-align: justify;\">Estamos jug\u00e1ndonos nuestra futura riqueza.\u00a0 Hay que aprender a volver a redistribuir. Y en eso los Estados han de jugar un papel que hasta ahora han intentado evitar por las malas experiencias tenidas en el siglo XX.\u00a0 Pero si se pretende triunfar, resolver los problemas a los que nos enfrentamos y dar una opci\u00f3n al futuro en paz y cohesi\u00f3n, hay que centrarse en la comunidad, en el individuo y en la realidad que nos rodea.<\/p>\n<p style=\"text-align: justify;\">Y tener presente que la historia es un activo para los pa\u00edses y las <strong>comunidades<\/strong>, indudablemente, pero tambi\u00e9n puede ser un problema si no se maneja inteligentemente.<\/p>\n<p style=\"text-align: justify;\">No se puede perder el foco en potenciar las clases medias y en tambi\u00e9n fomentar las infraestructuras que facilitan el crecimiento y expansi\u00f3n de estas clases medias. Estamos frente al cambio de un gran ciclo y quienes soportaran ese cambio de una mejor manera ser\u00e1n sin lugar a dudas las clases medias. China en este sentido, podr\u00eda llegar a ser un gran problema.<\/p>\n<p style=\"text-align: justify;\">Los j\u00f3venes hay que verlos como un dividendo demogr\u00e1fico. Pero\u2026 \u00bfest\u00e1n preparados? \u00bfse est\u00e1n preparando?<\/p>\n<p style=\"text-align: justify;\">La India, de quien tanto se habla como el pa\u00eds del futuro, tiene tambi\u00e9n un enorme problema potencial: s\u00f3lo un 50% de sus j\u00f3venes puede acceder a formaci\u00f3n superior.\u00a0 Y esto es algo que ocurre en Africa, en Latinoam\u00e9rica y en todos los pa\u00edses \u00e1rabes.<\/p>\n<p style=\"text-align: justify;\">Dejemos estos comentarios para la reflexi\u00f3n de cada uno\u2026<\/p>\n<p style=\"text-align: justify;\">Fue una magn\u00edfica comida y una oportunidad para conocer a un hombre que me pareci\u00f3 realmente extraordinario.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>A few days ago I had the opportunity, at the invitation of the Instituto de Empresa, to attend a lunch in Madrid chaired by the Deputy Prime Minister of Singapore, also Minister of Finance and Minister of Human Resources, Tharman Shanmugaratnam.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[6],"tags":[401,407,416,414,415,400,402,409,405,408,403,404,399,396,174,398,123,410,411,406,413,397,412],"class_list":["post-1024","post","type-post","status-publish","format-standard","hentry","category-emprendedor","tag-austeridad","tag-ciudadano","tag-clase-media","tag-cohesion","tag-comunidad","tag-confianza","tag-crecimiento","tag-crisis","tag-emerging-markets","tag-especulador","tag-global","tag-globalidad","tag-imf","tag-instituto-de-empresa","tag-libertad","tag-london-school-of-economics","tag-mercado","tag-movillidad-social","tag-oportunidades","tag-paises-emergentes","tag-paz","tag-singapur","tag-unidad-social"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/1024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/comments?post=1024"}],"version-history":[{"count":3,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/1024\/revisions"}],"predecessor-version":[{"id":1029,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/1024\/revisions\/1029"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/media?parent=1024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/categories?post=1024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/tags?post=1024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}