{"id":2188,"date":"2014-06-18T06:07:45","date_gmt":"2014-06-18T06:07:45","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=2188"},"modified":"2014-06-18T06:29:29","modified_gmt":"2014-06-18T06:29:29","slug":"amad-vuestros-enemigos","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/en\/amad-vuestros-enemigos\/","title":{"rendered":"Love your enemies"},"content":{"rendered":"<p>Este ha sido el <a title=\"Evangelio\" href=\"http:\/\/es.wikipedia.org\/wiki\/Evangelio\" target=\"_blank\">Evangelio<\/a> de ayer&#8230;<\/p>\n<p>Mt 5, 43-48: \u00ab<i style=\"color: #000000\">Hab\u00e9is o\u00eddo que se dijo: Amar\u00e1s a tu pr\u00f3jimo y odiar\u00e1s a tu enemigo. Pues yo os digo: Amad a vuestros enemigos y rogad por los que os persigan, para que se\u00e1is hijos de vuestro Padre celestial, que hace salir su sol sobre malos y buenos, y llover sobre justos e injustos. Porque si am\u00e1is a los que os aman, \u00bfqu\u00e9 recompensa vais a tener? \u00bfNo hacen eso mismo tambi\u00e9n los publicanos? Y si no salud\u00e1is m\u00e1s que a vuestros hermanos, \u00bfqu\u00e9 hac\u00e9is de particular? \u00bfNo hacen eso mismo tambi\u00e9n los gentiles? Vosotros, pues, sed perfectos como es perfecto vuestro Padre celestial\u00bb<\/i><\/p>\n<p>As\u00ed lo plantea <a title=\"Jesus Christ\" href=\"http:\/\/es.wikipedia.org\/wiki\/Cristo\" target=\"_blank\">Jesus Christ<\/a>. Nada de medias tintas.<\/p>\n<p><strong><em>\u00abAmad a vuestros enemigos y rogad por los que os persigan&#8230; porque si amais a los que os aman&#8230; \u00bfqu\u00e9\u00a0hac\u00e9is\u00a0de particular?\u00bb<\/em><\/strong><\/p>\n<p>Nunca Jesucristo plante\u00f3 que seguir sus ense\u00f1anzas fuera a ser f\u00e1cil.<\/p>\n<p>Cuando te acercas a El, si lo miras desde un punto de vista humano y racional, no es nada f\u00e1cil seguirle y mucho menos hacerlo como El quiere que lo hagamos. En algunos momentos&#8230;. es especialmente duro. Pero El lo tuvo claro. \u00ab&#8230;<em>el que me ame, guardar\u00e1 mis mandamientos y mi Padre le amar\u00e1<\/em>&#8230;\u00bb. Mira qu\u00e9 termina diciendo:<\/p>\n<p><strong>\"<em>Sed perfectos, como es perfecto vuestro Padre celestial<\/em>\".<\/strong><\/p>\n<p>Esta es la lecci\u00f3n. Lo escuch\u00e9 ayer y no puedo dejar de pensar en ello.<\/p>\n<p>Tambi\u00e9n en algun otro momento dijo que hab\u00eda venido a \u00ab&#8230;<em>salvar a los pecadores<\/em>&#8230;\u00bb. Sab\u00eda muy bien de nuestra debilidad.<\/p>\n<p>Seguir a Jesucristo en sus ense\u00f1anzas es dif\u00edcil pero da respuestas. Muchas respuestas. Y descanso al alma.<\/p>\n<p>No es teor\u00eda, es experiencia. Es realidad.<\/p>\n<figure id=\"attachment_2192\" aria-describedby=\"caption-attachment-2192\" style=\"width: 249px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2014\/06\/amad-a-los-que-os-odian.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-2192\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2014\/06\/amad-a-los-que-os-odian.jpeg\" alt=\"Amad a vuestros enemigos\" width=\"249\" height=\"203\" \/><\/a><figcaption id=\"caption-attachment-2192\" class=\"wp-caption-text\">Love your enemies<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Este ha sido el Evangelio de ayer&#8230; Mt 5, 43-48: \u00abHab\u00e9is o\u00eddo que se dijo: Amar\u00e1s a tu pr\u00f3jimo y odiar\u00e1s a tu enemigo. Pues yo os digo: Amad a vuestros enemigos y rogad por los que os persigan, para que se\u00e1is hijos de vuestro Padre celestial, que hace salir su sol sobre malos y&#8230;<\/p>","protected":false},"author":1,"featured_media":2195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7],"tags":[707,706,708,711,696,710,709,712],"class_list":["post-2188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-living","tag-amad","tag-amad-a-vuestros-enemigos","tag-enemigos","tag-evangelio","tag-jesucristo","tag-padre-celestial","tag-projimo","tag-san-mateo"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/2188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/comments?post=2188"}],"version-history":[{"count":8,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/2188\/revisions"}],"predecessor-version":[{"id":2200,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/posts\/2188\/revisions\/2200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/media\/2195"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/media?parent=2188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/categories?post=2188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/en\/wp-json\/wp\/v2\/tags?post=2188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}