{"id":1073,"date":"2012-10-23T11:47:44","date_gmt":"2012-10-23T11:47:44","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=1073"},"modified":"2013-06-09T12:41:49","modified_gmt":"2013-06-09T12:41:49","slug":"exito-de-pocoyo-en-youtube-facebook-y-dispositivos-moviles","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/es\/exito-de-pocoyo-en-youtube-facebook-y-dispositivos-moviles\/","title":{"rendered":"\u00c9xito de Pocoy\u00f3 en Youtube, Facebook y dispositivos m\u00f3viles"},"content":{"rendered":"<p style=\"text-align: justify;\">En <a href=\"http:\/\/www.zinkia.com\/\" target=\"_blank\">Zinkia<\/a> estamos de enhorabuena ya que nuestro querido <a href=\"http:\/\/www.pocoyo.com\/\" target=\"_blank\">Pocoy\u00f3<\/a> est\u00e1 arrasando en Internet. Desde que en el a\u00f1o 2010 este famoso personaje de animaci\u00f3n se convirtiera en partner oficial de <a href=\"http:\/\/www.youtube.com\/?tab=w1&amp;gl=ES\" target=\"_blank\">Youtube<\/a>, <strong>son ya m\u00e1s de m\u00e1s de 1.000 millones de reproducciones de la serie las que ha registrado este canal de v\u00eddeo online.<\/strong> Y no para de crecer <strong>con una media de 50 millones de visualizaciones al mes.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/Pocoyo_YouTube_mill_millones_FB_1millon.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1687\" alt=\"Pocoyo_YouTube_mill_millones_FB_1millon\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/Pocoyo_YouTube_mill_millones_FB_1millon.jpg\" width=\"800\" height=\"500\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/Pocoyo_YouTube_mill_millones_FB_1millon.jpg 800w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/Pocoyo_YouTube_mill_millones_FB_1millon-300x187.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--more-->Tras obtener estos fant\u00e1sticos resultados podemos afirmar que <strong>la red de canales que facilitan el contenido de Pocoy\u00f3 a diferentes pa\u00edses cuenta ya con m\u00e1s de 120.000 suscriptores\u00a0<\/strong> y puede ser visualizada en diferentes idiomas, entre los que destaca el ingl\u00e9s, el chino, el franc\u00e9s, el japon\u00e9s, el italiano o el turco, entre otros . Adem\u00e1s, el principal canal de esta red, <a href=\"http:\/\/www.youtube.com\/user\/pocoyotv\" target=\"_blank\">\u201cPocoyo TV<\/a>\u201d, <strong>tiene 100.000 suscriptores <\/strong>siendo Estados Unidos, M\u00e9xico, Espa\u00f1a y Brasil, donde las aventuras del famoso personaje y sus amigos poseen una mayor aceptaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Pero a\u00fan hay m\u00e1s razones para estar satisfechos. La p\u00e1gina oficial de <a href=\"http:\/\/www.facebook.com\/pocoyo\" target=\"_blank\">Pocoy\u00f3 en Facebook <\/a>tambi\u00e9n <strong>ha superado el mill\u00f3n de fans<\/strong>, lo que la convierte en la serie de animaci\u00f3n con\u00a0 el mayor n\u00famero de seguidores en esta red social en Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Asimismo, las aplicaciones para dispositivos m\u00f3viles con contenidos relacionados con Pocoy\u00f3, entre las que destacan <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.gigigo.android.pocoyize&amp;hl=es\" target=\"_blank\">Pocoyize<\/a>, <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.pocoyotvlite.google&amp;feature=more_from_developer#?t=W251bGwsMSwxLDEwMiwiY29tLnBvY295b3R2bGl0ZS5nb29nbGUiXQ..\" target=\"_blank\">Pocoy\u00f3 TV <\/a>o <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.gi.talkingpocoyopremium&amp;feature=related_apps#?t=W251bGwsMSwxLDEwOSwiY29tLmdpLnRhbGtpbmdwb2NveW9wcmVtaXVtIl0.\" target=\"_blank\">Talking Pocoy\u00f3<\/a>, han crecido de manera espectacular llegando a <strong>sumar m\u00e1s de dos millones de descargas.<\/strong><\/p>\n<p style=\"text-align: justify;\">Finalmente, no podemos olvidar el primer mundo virtual protagonizado por Pocoy\u00f3, <a href=\"http:\/\/www.mundopocoyo.com\/\">www.mundopocoyo.com<\/a> , que tambi\u00e9n est\u00e1 cosechando \u00e9xitos ya que <strong>cuenta en su haber con una comunidad de m\u00e1s de 750.000 usuarios registrados.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/08\/mundo-pocoyo.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-683\" alt=\"mundo pocoyo\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/08\/mundo-pocoyo.jpg\" width=\"1074\" height=\"851\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/08\/mundo-pocoyo.jpg 1074w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/08\/mundo-pocoyo-300x237.jpg 300w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/08\/mundo-pocoyo-1024x811.jpg 1024w\" sizes=\"(max-width: 1074px) 100vw, 1074px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Zinkia estamos de enhorabuena ya que nuestro querido Pocoy\u00f3 est\u00e1 arrasando en Internet. Desde que en el a\u00f1o 2010 este famoso personaje de animaci\u00f3n se convirtiera en partner oficial de Youtube, son ya m\u00e1s de m\u00e1s de 1.000 millones de reproducciones de la serie las que ha registrado este canal de v\u00eddeo online. Y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[5],"tags":[330,468,85,42,469,89,16,76,470,22,12],"class_list":["post-1073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pocoyo","tag-animacion","tag-dispositivo","tag-facebook","tag-internet","tag-movil","tag-online","tag-pocoyo-2","tag-serie","tag-video","tag-youtube","tag-zinkia-2"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":4,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"predecessor-version":[{"id":1688,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1073\/revisions\/1688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/media\/1687"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}