{"id":1077,"date":"2012-10-30T14:33:44","date_gmt":"2012-10-30T14:33:44","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=1077"},"modified":"2013-06-08T12:12:00","modified_gmt":"2013-06-08T12:12:00","slug":"fortalezas-de-espana-en-el-siglo-de-europa","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/es\/fortalezas-de-espana-en-el-siglo-de-europa\/","title":{"rendered":"Fortalezas de Espa\u00f1a, en El Siglo de Europa"},"content":{"rendered":"<p style=\"text-align: justify;\">La revista <a href=\"http:\/\/www.elsiglodeuropa.es\/\" target=\"_blank\">El Siglo de Europa<\/a> ha elaborado un extenso reportaje con las opiniones de diversos directivos de varias empresas, sobre cuales son a su juicio las fortalezas con las que cuenta Espa\u00f1a para salir adelante en estos momentos de crisis. Tuve el honor de ser invitado a vertir mis opiniones.\u00a0 Aqu\u00ed os las dejo para que pod\u00e1is leerlas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/EL-SIGLO.pdf\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1079\" title=\"EL SIGLO_P\u00e1gina_1\" alt=\"\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/EL-SIGLO_P\u00e1gina_1-239x300.jpg\" width=\"239\" height=\"300\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/EL-SIGLO_P\u00e1gina_1-239x300.jpg 239w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/EL-SIGLO_P\u00e1gina_1-818x1024.jpg 818w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2012\/10\/EL-SIGLO_P\u00e1gina_1.jpg 1597w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La revista El Siglo de Europa ha elaborado un extenso reportaje con las opiniones de diversos directivos de varias empresas, sobre cuales son a su juicio las fortalezas con las que cuenta Espa\u00f1a para salir adelante en estos momentos de crisis. Tuve el honor de ser invitado a vertir mis opiniones.\u00a0 Aqu\u00ed os las dejo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[9],"tags":[473,31,86,471,472],"class_list":["post-1077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-los-medios","tag-el-siglo","tag-empresas","tag-espana","tag-fortalezas","tag-opiniones"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/comments?post=1077"}],"version-history":[{"count":4,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1077\/revisions"}],"predecessor-version":[{"id":1082,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/posts\/1077\/revisions\/1082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/media\/1079"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/media?parent=1077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/categories?post=1077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/es\/wp-json\/wp\/v2\/tags?post=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}