{"id":387,"date":"2011-05-23T15:22:39","date_gmt":"2011-05-23T15:22:39","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=387"},"modified":"2011-05-23T15:22:39","modified_gmt":"2011-05-23T15:22:39","slug":"en-el-suplemento-ecobolsa-de-el-economista","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/fr\/en-el-suplemento-ecobolsa-de-el-economista\/","title":{"rendered":"Dans le suppl\u00e9ment Ecobolsa de El Economista"},"content":{"rendered":"<p>Samedi dernier, le journal <a href=\"http:\/\/www.eleconomista.es\" target=\"_blank\">The Economist <\/a>a publi\u00e9 dans son suppl\u00e9ment Ecobolsa une interview dans laquelle j'analyse le pr\u00e9sent et l'avenir de l'\u00e9conomie europ\u00e9enne. <a href=\"http:\/\/www.zinkia.com\" target=\"_blank\">Zinkia<\/a> et <a href=\"http:\/\/www.pocoyo.com\" target=\"_blank\">Pocoyo<\/a>.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/05\/Jose-Maria-Castillejo-en-Ecobnolsa.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-388\" title=\"Jose Maria Castillejo \u00e0 Ecobolsa\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/05\/Jose-Maria-Castillejo-en-Ecobnolsa-216x300.jpg\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/05\/Jose-Maria-Castillejo-en-Ecobnolsa-216x300.jpg 216w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/05\/Jose-Maria-Castillejo-en-Ecobnolsa-739x1024.jpg 739w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Samedi dernier, le journal El Economista a publi\u00e9 dans son suppl\u00e9ment Ecobolsa une interview dans laquelle j'analyse le pr\u00e9sent et l'avenir de Zinkia et Pocoy\u00f3.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[9],"tags":[95,79,10,16,12],"class_list":["post-387","post","type-post","status-publish","format-standard","hentry","category-en-los-medios","tag-ecobolsa","tag-el-economista","tag-entrevista","tag-pocoyo-2","tag-zinkia-2"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/posts\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":2,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/posts\/387\/revisions"}],"predecessor-version":[{"id":390,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/posts\/387\/revisions\/390"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/media?parent=387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/categories?post=387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/fr\/wp-json\/wp\/v2\/tags?post=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}