{"id":136,"date":"2011-04-28T14:29:12","date_gmt":"2011-04-28T14:29:12","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=136"},"modified":"2011-04-28T14:29:12","modified_gmt":"2011-04-28T14:29:12","slug":"edem-imparte-un-mba-de-manera-gratuita","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/ru\/edem-imparte-un-mba-de-manera-gratuita\/","title":{"rendered":"EDEM \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u043e\u0435 \u043e\u0431\u0443\u0447\u0435\u043d\u0438\u0435 \u043f\u043e \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043c\u0435 MBA"},"content":{"rendered":"<p style=\"text-align: justify;\">Si te dijera que una <a title=\"Escuela de negocios\" href=\"http:\/\/www.edem.es\/\">Escuela de Negocios<\/a> me ha llamado la atenci\u00f3n y que me parece sorprendente y muy inteligente lo que hacen, probablemente me mirar\u00edas con cara de incr\u00e9dulo. Preguntar\u00edas qu\u00e9 es exactamente lo que hacen y yo tendr\u00eda que responder que impartir un Master en Administraci\u00f3n de Empresas. Com\u00fanmente conocido como un\u00a0 <a title=\"MBA\" href=\"http:\/\/es.wikipedia.org\/wiki\/MBA\">MBA<\/a>.<!--more--><\/p>\n<p style=\"text-align: justify;\">Y\u2026 \u00bfd\u00f3nde est\u00e1 lo sorprendente?.<\/p>\n<p style=\"text-align: justify;\">Pues en que lo hacen gratis. S\u00ed, gratis.\u00a0 Los alumnos no pagan nada, ninguno de ellos por recibir el Master. Nada. G R A T I S. Y adem\u00e1s, no contentos con darles gratis el M\u00e1ster, le garantizan a cada uno de los alumnos que al terminar el curso, tendr\u00e1n trabajo. S\u00ed se\u00f1or, gratis y adem\u00e1s con trabajo al final del curso!.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/fotop3041.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-141\" title=\"fotop3041\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/fotop3041.jpg\" alt=\"\" width=\"264\" height=\"189\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Esto ya s\u00ed que es sorprendente, \u00bfverdad?.<\/p>\n<p style=\"text-align: justify;\">Como dec\u00eda un poco m\u00e1s arriba: una idea inteligente, de gente inteligente\u2026 para gente inteligente.<\/p>\n<p style=\"text-align: justify;\">Al ser gratis, la Escuela se reserva el derecho de admisi\u00f3n. Y para ser admitidos, los requerimientos a los futuros alumnos son muy concretos: magn\u00edfico expediente escolar \u2013pr\u00e1cticamente de sobresaliente-, biling\u00fcismo y dotes especiales.<\/p>\n<p style=\"text-align: justify;\">En la \u00faltima edici\u00f3n pasaron el corte m\u00e1s de 400 potenciales alumnos y de ellos se seleccion\u00f3 a 25.<\/p>\n<p style=\"text-align: justify;\">\u00bfAlguna empresa quiere conocer los nombres de los 375 a los que no se seleccion\u00f3? Estoy seguro que m\u00e1s de una dar\u00eda dinero por esa lista. Pues imaginemos ahora qu\u00e9 no se dar\u00eda por uno de esos 25 que pasaron el corte y que adem\u00e1s han recibido su M\u00e1ster.<\/p>\n<p style=\"text-align: justify;\">Desde luego nosotros en <a title=\"\u0437\u0438\u043d\u043a\u0438\u044f\" href=\"http:\/\/www.zinkia.com\">Zinkia<\/a> nos hemos puesto en la lista para poder contar con alguno de los futuros posgraduados por<a title=\"escuela de negocios\" href=\"http:\/\/www.edem.es\/\"> EDEM<\/a>.<\/p>\n<p style=\"text-align: justify;\">Mi enhorabuena m\u00e1s sincera para Manuel Palma, Presidente de EDEM, Hortensia Roig, Responsable del M\u00e1ster y Antonio Noblejas, Director General.<\/p>\n<p style=\"text-align: justify;\">Esto son ejemplos de <span style=\"text-decoration: underline;\"><strong>emprendedores<\/strong><\/span>: en un sector con una competencia feroz han visto un nicho claro, se han metido en el y est\u00e1n haciendo un incre\u00edble trabajo con fant\u00e1sticos resultados. Van por la sexta edici\u00f3n. Mi enhorabuena otra vez.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Si te dijera que una Escuela de Negocios me ha llamado la atenci\u00f3n y que me parece sorprendente y muy inteligente lo que hacen, probablemente me mirar\u00edas con cara de incr\u00e9dulo. Preguntar\u00edas qu\u00e9 es exactamente lo que hacen y yo tendr\u00eda que responder que impartir un Master en Administraci\u00f3n de Empresas. Com\u00fanmente conocido como un\u00a0&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-136","post","type-post","status-publish","format-standard","hentry","category-emprendedor"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":2,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"predecessor-version":[{"id":143,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/136\/revisions\/143"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}