{"id":243,"date":"2011-04-29T23:20:32","date_gmt":"2011-04-29T23:20:32","guid":{"rendered":"http:\/\/josemariacastillejo.com\/?p=243"},"modified":"2013-06-07T21:23:25","modified_gmt":"2013-06-07T21:23:25","slug":"juan-pablo-ii","status":"publish","type":"post","link":"https:\/\/josemariacastillejo.com\/ru\/juan-pablo-ii\/","title":{"rendered":"Juan Pablo II"},"content":{"rendered":"<p style=\"text-align: justify;\">Con motivo, este fin de semana, de la Beatificaci\u00f3n de <strong>Juan Pablo II<\/strong>, no puedo dejar de escribir unas l\u00edneas para expresar mi profunda admiraci\u00f3n por la persona de <strong>Karol Wojtyla<\/strong>, as\u00ed como por el impresionante testimonio de vida que nos dio a todos los que tuvimos la oportunidad de compartir nuestros tiempos con los suyos.<!--more--><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/Ver-Beatificacion-de-Juan-Pablo-II-en-VIVO.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-253\" title=\"Ver Beatificacion de Juan Pablo II en VIVO\" alt=\"\" src=\"http:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/Ver-Beatificacion-de-Juan-Pablo-II-en-VIVO-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/Ver-Beatificacion-de-Juan-Pablo-II-en-VIVO-300x200.jpg 300w, https:\/\/josemariacastillejo.com\/wp-content\/uploads\/2011\/04\/Ver-Beatificacion-de-Juan-Pablo-II-en-VIVO.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Tuve adem\u00e1s la enorme fortuna de conocerlo personalmente.<\/p>\n<p style=\"text-align: justify;\">La primera vez que lo v\u00ed fue desde la multitud en su primera visita a Espa\u00f1a, el 1 de Noviembre de 1982, en Alba de Tormes y recuerdo el d\u00eda aquel como si fuera ayer. Por lo arrollador de su personalidad y&#8230; por el fr\u00edo que pasamos mientras esperamos que llegara el Papa junto al r\u00edo Tormes y entre la bruma!. Era realmente impresionante la ilusi\u00f3n, la alegr\u00eda y el \u00e1nimo de hacer algo por los dem\u00e1s que transmit\u00eda con su ejemplo y sus palabras.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s adelante tuve la oportunidad de saludarlo personalmente en una ocasi\u00f3n en Roma, en la Sacrist\u00eda de San Pedro, mientras estudiaba all\u00ed. La \u00faltima vez que le v\u00ed y tuve oportunidad de saludarle fu\u00e9 en sus Apartamentos Privados, en la <a href=\"http:\/\/www.vatican.va\">Ciudad del Vaticano<\/a>, donde tuve la enorme fortuna de poder acudir y recibir su Bendici\u00f3n junto con mi esposa, pocos d\u00edas despu\u00e9s de terminar nuestro Viaje de Novios. Cada vez que me encontr\u00e9 con el me transmiti\u00f3 siempre lo mismo: paz, fortaleza, alegr\u00eda y determinaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Creo que pocos hombres en nuestra historia contempor\u00e1nea mundial han calado, transmitido y movido tantas voluntades, almas y corazones. Fue un l\u00edder humano cercano, de carne y hueso con el que era f\u00e1cil adem\u00e1s llegar a identificarse. Transmit\u00eda de una manera ejemplar y con una enorme sencillez la importancia de vivir en nuestro mundo, en el d\u00eda a d\u00eda, sin dejar de pensar en el m\u00e1s all\u00e1.<\/p>\n<p style=\"text-align: justify;\">Abri\u00f3 las puertas de la <a href=\"http:\/\/www.conferenciaepiscopal.es\">Iglesia Cat\u00f3lica<\/a>\u00a0como nunca antes otros lo hab\u00edan hecho a todos los hermanos en la fe de Cristo y a todos los hermanos de otras religiones y otras creencias. A todos tendi\u00f3 una mano, sin dejar de ser fiel a las ense\u00f1anzas y a la doctrina de la Iglesia.<\/p>\n<p style=\"text-align: justify;\">Como todos en este mundo, tiene y tendr\u00e1 cr\u00edticos. No me cabe la menor duda. Pero pocos hombres con una ideas, una vida y una predicaci\u00f3n tan clara han sido capaces de acercarse, gozar de la amistad y del respeto de personas tan alejadas de sus ideales y predicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Fue un gran hombre de Dios que a m\u00ed y estoy seguro que a muchos otros, nos ayud\u00f3 a acercarnos y conocer m\u00e1s a Dios.<\/p>\n<p style=\"text-align: justify;\">\u00a1Muchas gracias Juan Pablo! \u00a1Ruega por nosotros!!<\/p>","protected":false},"excerpt":{"rendered":"<p>Con motivo, este fin de semana, de la Beatificaci\u00f3n de Juan Pablo II, no puedo dejar de escribir unas l\u00edneas para expresar mi profunda admiraci\u00f3n por la persona de Karol Wojtyla, as\u00ed como por el impresionante testimonio de vida que nos dio a todos los que tuvimos la oportunidad de compartir nuestros tiempos con los&#8230;<\/p>","protected":false},"author":1,"featured_media":1554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7],"tags":[27,28,26,29],"class_list":["post-243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-living","tag-beatificacion","tag-iglesia-catolica","tag-juan-pablo-ii","tag-vaticano"],"_links":{"self":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":6,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/243\/revisions"}],"predecessor-version":[{"id":247,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/posts\/243\/revisions\/247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/media\/1554"}],"wp:attachment":[{"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/media?parent=243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/categories?post=243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josemariacastillejo.com\/ru\/wp-json\/wp\/v2\/tags?post=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}